{"id":71770,"date":"2022-09-24T10:37:31","date_gmt":"2022-09-24T14:37:31","guid":{"rendered":"https:\/\/panm360.com\/?post_type=agenda&#038;p=71770"},"modified":"2022-09-24T10:41:39","modified_gmt":"2022-09-24T14:41:39","slug":"les-freres-sissokho-au-club-balattou","status":"publish","type":"agenda","link":"https:\/\/panm360.com\/en\/agenda\/les-freres-sissokho-au-club-balattou\/","title":{"rendered":"Les Fr\u00e8res Sissokho au Club Balattou"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les Fr\u00e8res Sissokho, Sadio, Fa et Noumoucounda, originaires du S\u00e9n\u00e9gal, sont les descendants d\u2019une des grandes familles de griots mandingues d\u2019Afrique de l\u2019Ouest. Ils rendent hommage \u00e0 la tradition en insufflant une bonne dose de cr\u00e9ativit\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Multi-instrumentistes, ma\u00eetres de la kora et des percussions, ils manient leurs instruments et leurs voix avec une dext\u00e9rit\u00e9 et un panache d\u00e9sarmants.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Venez d\u00e9couvrir ou red\u00e9couvrir cette culture musicale riche de plusieurs mill\u00e9naires d\u2019histoires et de rythmes envo\u00fbtants dans une ambiance chaleureuse et festive.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Sissokho brothers, Sadio, Fa and Noumoucounda, originally from Senegal, are descendants of one of the great families of Mandingo griots in West Africa. They pay homage to tradition by injecting a good dose of creativity.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Multi-instrumentalists, masters of the kora and percussion, they handle their instruments and voices with disarming dexterity and panache.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Come and discover or rediscover this musical culture, rich in history and bewitching rhythms, in a warm and festive atmosphere.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BILLETS EN VENTE \u00c0 LA PORTE!<\/strong><\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/OTU8dH0dCa8\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Ce contenu provient des Productions Nuits d\u2019Afrique et est adapt\u00e9 par PAN M 360.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Fr\u00e8res Sissokho, Sadio, Fa et Noumoucounda, originaires du S\u00e9n\u00e9gal, sont les descendants d\u2019une des grandes familles de griots mandingues d\u2019Afrique de l\u2019Ouest. Ils rendent hommage \u00e0 la tradition en insufflant une bonne dose de cr\u00e9ativit\u00e9.&nbsp; Multi-instrumentistes, ma\u00eetres de la kora et des percussions, ils manient leurs instruments et leurs voix avec une dext\u00e9rit\u00e9 et [&hellip;]<\/p>\n","protected":false},"author":936,"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[4322],"tags":[],"generale":[3814],"genre":[],"pays":[3863],"salle":[7551],"ville":[7246],"class_list":["post-71770","agenda","type-agenda","status-publish","format-standard","hentry","category-listings-360","generale-lire-en","pays-senegal-en","salle-club-balattou-en","ville-montreal-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Fr\u00e8res Sissokho au Club Balattou - PAN M 360<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/panm360.com\/en\/agenda\/les-freres-sissokho-au-club-balattou\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Fr\u00e8res Sissokho au Club Balattou - PAN M 360\" \/>\n<meta property=\"og:description\" content=\"Les Fr\u00e8res Sissokho, Sadio, Fa et Noumoucounda, originaires du S\u00e9n\u00e9gal, sont les descendants d\u2019une des grandes familles de griots mandingues d\u2019Afrique de l\u2019Ouest. Ils rendent hommage \u00e0 la tradition en insufflant une bonne dose de cr\u00e9ativit\u00e9.&nbsp; Multi-instrumentistes, ma\u00eetres de la kora et des percussions, ils manient leurs instruments et leurs voix avec une dext\u00e9rit\u00e9 et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/panm360.com\/en\/agenda\/les-freres-sissokho-au-club-balattou\/\" \/>\n<meta property=\"og:site_name\" content=\"PAN M 360\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/panm360\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-24T14:41:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/panm360.com\/wp-content\/uploads\/2022\/06\/freres-sissokho-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PANM360\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/panm360.com\\\/en\\\/agenda\\\/les-freres-sissokho-au-club-balattou\\\/\",\"url\":\"https:\\\/\\\/panm360.com\\\/en\\\/agenda\\\/les-freres-sissokho-au-club-balattou\\\/\",\"name\":\"Les Fr\u00e8res Sissokho au Club Balattou - PAN M 360\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/panm360.com\\\/en\\\/#website\"},\"datePublished\":\"2022-09-24T14:37:31+00:00\",\"dateModified\":\"2022-09-24T14:41:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/panm360.com\\\/en\\\/agenda\\\/les-freres-sissokho-au-club-balattou\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/panm360.com\\\/en\\\/agenda\\\/les-freres-sissokho-au-club-balattou\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/panm360.com\\\/en\\\/agenda\\\/les-freres-sissokho-au-club-balattou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/panm360.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/panm360.com\\\/en\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les Fr\u00e8res Sissokho au Club Balattou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/panm360.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/panm360.com\\\/en\\\/\",\"name\":\"PAN M 360\",\"description\":\"Le m\u00e9dia num\u00e9rique de la musique !\",\"publisher\":{\"@id\":\"https:\\\/\\\/panm360.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/panm360.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/panm360.com\\\/en\\\/#organization\",\"name\":\"PAN M 360\",\"url\":\"https:\\\/\\\/panm360.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/panm360.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/panm360.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/PAN-M360_Logo_RGB.jpg\",\"contentUrl\":\"https:\\\/\\\/panm360.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/PAN-M360_Logo_RGB.jpg\",\"width\":1663,\"height\":631,\"caption\":\"PAN M 360\"},\"image\":{\"@id\":\"https:\\\/\\\/panm360.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/panm360\\\/\",\"https:\\\/\\\/x.com\\\/PANM360\",\"https:\\\/\\\/www.instagram.com\\\/panm360\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/panm360\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHEFHd3UhIrV6EJ3ltzVKOA?view_as=subscriber\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Fr\u00e8res Sissokho au Club Balattou - PAN M 360","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/panm360.com\/en\/agenda\/les-freres-sissokho-au-club-balattou\/","og_locale":"en_US","og_type":"article","og_title":"Les Fr\u00e8res Sissokho au Club Balattou - PAN M 360","og_description":"Les Fr\u00e8res Sissokho, Sadio, Fa et Noumoucounda, originaires du S\u00e9n\u00e9gal, sont les descendants d\u2019une des grandes familles de griots mandingues d\u2019Afrique de l\u2019Ouest. Ils rendent hommage \u00e0 la tradition en insufflant une bonne dose de cr\u00e9ativit\u00e9.&nbsp; Multi-instrumentistes, ma\u00eetres de la kora et des percussions, ils manient leurs instruments et leurs voix avec une dext\u00e9rit\u00e9 et [&hellip;]","og_url":"https:\/\/panm360.com\/en\/agenda\/les-freres-sissokho-au-club-balattou\/","og_site_name":"PAN M 360","article_publisher":"https:\/\/www.facebook.com\/panm360\/","article_modified_time":"2022-09-24T14:41:39+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/panm360.com\/wp-content\/uploads\/2022\/06\/freres-sissokho-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PANM360","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/panm360.com\/en\/agenda\/les-freres-sissokho-au-club-balattou\/","url":"https:\/\/panm360.com\/en\/agenda\/les-freres-sissokho-au-club-balattou\/","name":"Les Fr\u00e8res Sissokho au Club Balattou - PAN M 360","isPartOf":{"@id":"https:\/\/panm360.com\/en\/#website"},"datePublished":"2022-09-24T14:37:31+00:00","dateModified":"2022-09-24T14:41:39+00:00","breadcrumb":{"@id":"https:\/\/panm360.com\/en\/agenda\/les-freres-sissokho-au-club-balattou\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/panm360.com\/en\/agenda\/les-freres-sissokho-au-club-balattou\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/panm360.com\/en\/agenda\/les-freres-sissokho-au-club-balattou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/panm360.com\/en\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/panm360.com\/en\/agenda\/"},{"@type":"ListItem","position":3,"name":"Les Fr\u00e8res Sissokho au Club Balattou"}]},{"@type":"WebSite","@id":"https:\/\/panm360.com\/en\/#website","url":"https:\/\/panm360.com\/en\/","name":"PAN M 360","description":"Le m\u00e9dia num\u00e9rique de la musique !","publisher":{"@id":"https:\/\/panm360.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/panm360.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/panm360.com\/en\/#organization","name":"PAN M 360","url":"https:\/\/panm360.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/panm360.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/panm360.com\/wp-content\/uploads\/2019\/12\/PAN-M360_Logo_RGB.jpg","contentUrl":"https:\/\/panm360.com\/wp-content\/uploads\/2019\/12\/PAN-M360_Logo_RGB.jpg","width":1663,"height":631,"caption":"PAN M 360"},"image":{"@id":"https:\/\/panm360.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/panm360\/","https:\/\/x.com\/PANM360","https:\/\/www.instagram.com\/panm360\/","https:\/\/www.linkedin.com\/company\/panm360\/","https:\/\/www.youtube.com\/channel\/UCHEFHd3UhIrV6EJ3ltzVKOA?view_as=subscriber"]}]}},"_links":{"self":[{"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/agenda\/71770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/agenda"}],"about":[{"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/types\/agenda"}],"author":[{"embeddable":true,"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/users\/936"}],"wp:attachment":[{"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/media?parent=71770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/categories?post=71770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/tags?post=71770"},{"taxonomy":"generale","embeddable":true,"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/generale?post=71770"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/genre?post=71770"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/pays?post=71770"},{"taxonomy":"salle","embeddable":true,"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/salle?post=71770"},{"taxonomy":"ville","embeddable":true,"href":"https:\/\/panm360.com\/en\/wp-json\/wp\/v2\/ville?post=71770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}